{"id":826,"date":"2023-06-25T20:16:44","date_gmt":"2023-06-25T20:16:44","guid":{"rendered":"https:\/\/aswittepartg.de\/servicios\/weiterbildung-aktuelles\/"},"modified":"2024-08-18T14:05:39","modified_gmt":"2024-08-18T14:05:39","slug":"weiterbildung-aktuelles","status":"publish","type":"page","link":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/","title":{"rendered":"Fortbildung &amp; Aktuelles"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"826\" class=\"elementor elementor-826 elementor-240\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3dcf21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3dcf21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b08e82\" data-id=\"6b08e82\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6161015 elementor-widget elementor-widget-heading\" data-id=\"6161015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fortbildung &amp; Aktuelles<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12fc7a3 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12fc7a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-34188e8\" data-id=\"34188e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22151c0 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-spacer\" data-id=\"22151c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f10fafc elementor-widget elementor-widget-text-editor\" data-id=\"f10fafc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Aktuelles<\/h2><p>\u00c4nderungen unserer AGB in \u00a7 3c zu Mindestauftragswerten &#8211; 2013<\/p><p>\u00c4nderungen unserer AGB in \u00a7 3a zu den Berechnungsgrundlagen unserer Leistungen und \u00a7 4a und 4d zu den Zahlungskonditionen &#8211; 2014<\/p><p>\u00c4nderungen unserer AGB in \u00a7 5 zu den R\u00fccktrittsregelungen und \u00a7 7 zu Stornierungsgeb\u00fchren &#8211; 2014<\/p><p>\u00c4nderung unserer AGB in \u00a7 4b &#8211; 2014<\/p><p>\u00c4nderung unserer AGB in \u00a7 4b &#8211; 2016<\/p><p>Update der angebotenen Zahlungsweisen: \u00dcberweisung, Skrill, XOOM, TransferWise oder Payoneer stehen ggf. zur Verf\u00fcgung &#8211; 2018<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d9a78d\" data-id=\"0d9a78d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4e488e elementor-widget elementor-widget-image\" data-id=\"c4e488e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"516\" height=\"386\" src=\"https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/hoersaal-tmp.jpg\" class=\"attachment-full size-full wp-image-523\" alt=\"\" srcset=\"https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/hoersaal-tmp.jpg 516w, https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/hoersaal-tmp-300x224.jpg 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-06fc3f9 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06fc3f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-963bcea\" data-id=\"963bcea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d3def1 elementor-widget elementor-widget-text-editor\" data-id=\"1d3def1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Anpassung unserer Datenschutzerkl\u00e4rung, deutsche Version, an die EU-weit geltende DSGVO &#8211; 2018<\/p>\n<p>42 neue gro\u00dfe SDL MultiTerm-Termbanken angelegt &#8211; 2019<\/p>\n<p>8j\u00e4hriges Firmenjubil\u00e4um &#8211; 07.04.2019<\/p>\n<p>Etwa 2000 Termbankeintr\u00e4ge hinzugef\u00fcgt, dabei Importe in 16 Termbanken durchgef\u00fchrt &#8211; November 2019. Etwa 4350 Termbankeintr\u00e4ge hinzugef\u00fcgt &#8211; April 2020.&nbsp;Neue Termbank Steuern und Zoll, angelegt im Oktober 2020, 2750 Eintr\u00e4ge.<\/p>\n<p>Informationen \u00fcber Arten von Marken, die f\u00fcr unsere Kunden aus dem Gewerblichen Rechtsschutz von Interesse sein k\u00f6nnten&nbsp;<a href=\"https:\/\/euipo.europa.eu\/ohimportal\/de\/trade-marks-examples\" data-extlink=\"\">https:\/\/euipo.europa.eu\/ohimportal\/de\/trade-marks-examples<\/a><\/p>\n<p>Wichtige Neuerungen: Markenrechtsmodernisierungsgesetz zur Umsetzung der neuen EU-Markenrechtsrichtlinie trat zum 14. Januar 2019 in Kraft<\/p>\n<p>Es wurden mit dem Inkrafttreten des MaMoG in Dtschld. ganz neue Markenarten wie Gew\u00e4hrleistungsmarken und graphische Marken wie Videoszenen oder Bewegungsmarken eingef\u00fchrt. In seiner Tragweite vergleichbar dem dt. Bilanzrechtsmodernisierungsgesetz<br>\/BilMoG in der Rechnungslegung, d\u00fcrfte dies eine bedeutende Neuerung der Gesetzesgrundlagen des Markenschutzes sein.&nbsp;<br><a href=\"https:\/\/www.dpma.de\/marken\/markenschutz\/mamog\/markenrechtsreform\/index.html\" data-extlink=\"\">https:\/\/www.dpma.de\/marken\/markenschutz\/mamog\/markenrechtsreform\/index.html<\/a><\/p>\n<p><a href=\"https:\/\/oos.sdl.com\/asp\/products\/certified\/index.asp?userid=1947d4c0-055c-4813-8131-2d98779b053f\" data-extlink=\"\">Astrids j\u00fcngst erworbene SDL\/RWS Trados Studio- und MultiTerm-Zertifizierungen&nbsp;<\/a>(mehr dazu am Ende dieser Seite unter Arbeit mit \u00dcbersetzungsumgebungen) f\u00fcr neuere Versionen der beiden Programme k\u00f6nnen dort unter dem Link zum Nutzerportal von SDL\/RWS eingesehen werden <a href=\"https:\/\/oos.sdl.com\/asp\/products\/certified\/index.asp?userid=7900\" target=\"_blank\" rel=\"noopener\">hier.<\/a><\/p>\n<p>SDL\/RWS Trados Studio 2021 and SDL\/RWS MultiTerm 2021 eingef\u00fchrt, zum Teil noch im Parallelbetrieb mit SDL Trados 2019 &#8211; September 2020<\/p>\n<p>Etwa 2800 Termbankeintr\u00e4ge hinzugef\u00fcgt, diverse Termbanken &#8211; Mai 2021.&nbsp;<\/p>\n<p><br><\/p>\n<p>Hier drei interessante Apps als Plug-ins f\u00fcr RWS Trados Studio, bei uns in Benutzung:&nbsp;<br><a href=\"https:\/\/appstore.rws.com\/plugin\/63\/\" data-extlink=\"\">https:\/\/appstore.rws.com\/plugin\/63\/<\/a>&nbsp; &nbsp; &nbsp; Integrated Search Views, gleichzeitiges Durchsuchen einer Vielzahl von XLIFFs nach Suchbegriffen in Studio. Unsere Wertung 3,5 von 5 Sternen.<br><a href=\"https:\/\/appstore.sdl.com\/language\/app\/rapid-add-term\/1050\/\" data-extlink=\"\">https:\/\/appstore.sdl.com\/language\/app\/rapid-add-term\/1050\/<\/a>&nbsp; Rapid Add Term, schnelles Hinzuf\u00fcgen von Termbankeintr\u00e4gen in die Standardtermbank Deines Studio-Projekts.&nbsp;Unsere Wertung 5 von 5 Sternen.<br><a href=\"https:\/\/appstore.rws.com\/plugin\/4\/\" data-extlink=\"\">https:\/\/appstore.rws.com\/plugin\/4\/<\/a>&nbsp; &nbsp;Web Lookup!, durchsucht Google, Google Define, Pons, IATE, Wikipedia usw. nach Definitionen oder Begriffs\u00fcbersetzungen. Unsere Bewertung 3 von 5 Sternen.<\/p>\n<p><\/p>\n<p>Wechsel der Verm\u00f6gensschadenhaftpflichtversicherung zum 10.6.2021, R + V Versicherung -&gt; Hiscox SA.&nbsp;<\/p>\n<p><\/p>\n<p>Update auf Windows 11 auf beiden Computern (04\/2022).<\/p>\n<p>Unsere K\u00fcndigung der Verm\u00f6gensschadenhaftpflicht (06\/2023).&nbsp;<strong>Unsere Haftung ist auf den Auftragswert beschr\u00e4nkt<\/strong>.<\/p>\n<p><span style=\"font-style: inherit; font-weight: inherit;\">Verm\u00f6gensschadenhaftpflicht bei Hiscox SA neu abgeschlossen (06\/2024). Haftung bis 75.000 Euro je Schadenfall.<\/span><\/p>\n<p><span style=\"font-style: inherit; font-weight: inherit;\">RWS Trados Studio 2024 eingef\u00fchrt.<\/span><\/p>\n<p><span style=\"font-style: inherit; font-weight: inherit;\"><br><\/span><\/p>\n<div><strong>Informationen zu den Fachgebieten Immobilienwirtschaft und Bauwesen (10\/2022):<\/strong><\/div>\n<div><strong>Der Immobilienmarkt war zu keinem Punkt in den letzten 50 Jahren so spannend, wie wir ihn zu diesem Zeitpunkt erleben, und wir beobachten die Marktaktivit\u00e4ten mit.<\/strong><\/div>\n<div>&nbsp;<\/div>\n<div>Astrids Vater war in der Bauindustrie und besa\u00df f\u00fcr einige Zeit, insbesondere in Schottland in den 80ern und fr\u00fchen 90ern Jahren, ein Bauunternehmen, das norwegische Holzrahmenh\u00e4user gebaut und verkauft hat. Astrid hat zu Hause t\u00e4glich Gespr\u00e4che \u00fcber die Konstruktion und Aspekte der Bauindustrie mitangeh\u00f6rt und so viel \u00fcber das Bauen mit Holz gelernt. Nach ihrem sp\u00e4teren Umzug nach Deutschland hat ihr Vater dann, insbesondere im Rahmen ihrer Wohnungssuche, detaillierte Vergleiche zwischen der britischen und der deutschen Bauindustrie und deren Regeln angestellt.<\/div>\n<div>&nbsp;<\/div>\n<div>Im Laufe unserer \u2013 anfangs unterschiedlich verlaufenden, jedoch relativ bald zusammenf\u00fchrenden \u2013 Wege als \u00dcbersetzer, haben wir eine betr\u00e4chtliche Zahl von Mietvertr\u00e4gen \u00fcbersetzt \u2013 deutsche, \u00f6sterreichische und schweizerische. Dazu haben wir auch gelegentlich notariell beurkundete Wohnungskaufvertr\u00e4ge \u00fcbersetzt. Hier waren auch die besuchten Fortbildungen und die ehemalige Gasth\u00f6rerschaft an der Uni von Vorteil (siehe unten, Strg + F Suche nach \u00abImmo\u00bb). Es kamen dann sp\u00e4ter Auftr\u00e4ge im Bereich Bauwesen hinzu, wie z. B. Baubeschreibungen, und sogar detaillierte Baubeschreibungen zu aufwendiger konstruierten Geb\u00e4uden, dann auch u. a. mit zahlreichen Sicherheitsaspekten, und auch Auftr\u00e4ge zu B\u00fcro- und Gesch\u00e4ftsgeb\u00e4uden mit sehr spezifischen Zwecken.<\/div>\n<div>&nbsp;<\/div>\n<div>Wir haben w\u00e4hrend dieser Aktivit\u00e4ten (wie in allen anderen Bereichen, in denen wir \u00fcbersetzen) unsere fachlich spezialisierten Termbanken weiterentwickelt. Mittlerweile sind unsere Termbanken \u2013 insbesondere die f\u00fcr Immobilien und die Bauindustrie \u2013 sehr n\u00fctzlich f\u00fcr weitere Auftr\u00e4ge in diesem Bereich, sodass wir immer die richtigen Begriffe f\u00fcr Ihr Projekt finden werden.<\/div>\n<div>&nbsp;<\/div>\n<div>In diesen Zeiten, in denen viel \u00fcber Immobilien, Unterk\u00fcnfte und das Design der Geb\u00e4ude der Zukunft \u2013 u. a. im Bereich neuer Formen der Energieversorgung \u2013 geredet wird, sind wir in der Lage, nicht zuletzt mit Unterst\u00fctzung unseres Freiberufler-Netzwerks, Ihr Material in diesem Bereich f\u00fcr Sie \u2013 zwischen Deutsch, Englisch, Franz\u00f6sisch, Spanisch und Portugiesisch \u2013 kompetent zu \u00fcbersetzen \u2013 zumal wir auch \u00fcber Erfahrung im Bereich Energiewirtschaft verf\u00fcgen, und die aktuellen Entwicklungen in diesem Bereich verfolgen.<\/div>\n<div>&nbsp;<\/div>\n<h2>&nbsp;<\/h2>\n<h2>Besuchte Fortbildungen<\/h2>\n<p><strong>\u00dcbersetzen im Bereich Gewerbliche Schutzrechte<\/strong><\/p>\n<p>\u00dcbersetzen im Bereich Gewerblicher Rechtsschutz EN &gt; DE (BD\u00dc) \u2013 2011<\/p>\n<p>Gewerblicher Rechtsschutz in England (4,5st\u00fcndiges Seminar in Gro\u00dfbritannien), David Hutchins, Solicitor, Lexacom Legal Training Services &#8211; 2012<\/p>\n<p>Patentrecht: Europ\u00e4isches Einheitspatent, Einheitliches Patentgericht und Londoner \u00dcbereinkommen; IPC (Internationale Patentklassifikation) &#8211; BD\u00dc-Konferenz 2012<\/p>\n<p><strong>Juristische \u00dcbersetzung Englisch, im Wesentlichen kodifiziertes, auf r\u00f6mischem Recht basierendes deutsches Recht &lt;&gt; Common Law (\u00fcberwiegend nicht kodifiziertes Pr\u00e4zedenzrecht), insbesondere Englands\/von Wales und der USA<\/strong><\/p>\n<p>Gasth\u00f6rer Uni Bielefeld: Schuldrecht, mehrere Semester Legal English and English Law, Seminar Familienrecht, Seminar Liegenschaftsrecht (Immobiliarsachenrecht) &#8211; 2010-2012<\/p>\n<p>Webinar einer kanadischen Rechtsanw\u00e4ltin zur englischen Fachsprache Erbrecht (US-Englisch) \u2013 2011<\/p>\n<p>US-Gerichtsverfassung &amp; Zivilprozess- und Strafverfahrensrecht, Vertragsrecht sowie Gesellschaftsrecht: zwei Tage in D\u00fcsseldorf bei dem Lehrstuhlinhaber f\u00fcr Anglo-Amerikanisches Recht einer deutschen Uni mit einem LL.M. (Master of Laws, ein Postgraduiertenabschluss v.a. f\u00fcr Juristen) der Harvard University, in Texas als Anwalt zugelassen (ATICOM) \u2013 2012<\/p>\n<p>Englisches und amerikanisches Gesellschaftsrecht (BD\u00dc) &#8211; 2012<\/p>\n<p>Englisches Strafrecht und Strafverfahrensrecht (3st\u00fcndiges Webinar), David Hutchins, Solicitor (nicht pl\u00e4dierender Anwalt), Lexacom Legal Training Services \u2013 2012<\/p>\n<p>Sachenrecht in England (4,5st\u00fcndiges Seminar in Gro\u00dfbritannien), David Hutchins &#8211; 2012<\/p>\n<p>Webinar Englisches Arbeitsrecht, David Hutchins, Lexacom Legal<br>Training Services &#8211; 2012<\/p>\n<p>Seminar Englisches Immobilienrecht bei einem zweisprachigen Barrister (Rechtsanwalt bei h\u00f6heren Gerichten) sowie \u00dcbersetzungstraining DE &lt;&gt; EN (BD\u00dc), 2013<\/p>\n<p>3 Webinare in Rechtsvergleichung Deutschland &#8211; England\/Wales sowie der Theorie und Praxis der juristischen \u00dcbersetzung (Rechtstheorie, Gerichtsverfassungen, Prozessrecht, Vertragsrecht &amp; Satzungen, Strafrecht, Arbeitsrecht, Gesellschaftsrecht) bei einer Dozentin der City University, London, und Rechtsanw\u00e4ltin sowie einem zweisprachigen Barrister, eCPD Webinars &#8211; 2013<\/p>\n<p>Tagesseminar mit David Hutchins, Solicitor, zum Englischen Recht mit den Schwerpunkten Common Law\/Equity-Recht (Billigkeitsrecht)\/auf dem R\u00f6mischen Recht beruhendes, weitgehend kodifiziertes kontinentaleurop\u00e4isches Recht, Englische Gerichtsverfassung\/sonstige Gerichtsterminologie\/Berufsbilder der Juristerei einschlie\u00dflich Richterstand\/Zivil- und Strafverfahrensrecht\/Einblicke in die T\u00e4tigkeitsfelder von Solicitor &amp; Barrister, Deliktsrecht (Recht der unerlaubten Handlungen), Vertragsrecht, ATICOM &#8211; 2014<\/p>\n<p>Die Unternehmensinsolvenz<\/p>\n<p>Deutschland<\/p>\n<ul>\n<li>Regelinsolvenz \u2013 Abgrenzung zur Verbraucherinsolvenz<\/li>\n<li>Er\u00f6ffnungsgr\u00fcnde, \u00a7\u00a7 17 \u2013 19 InsO<\/li>\n<li>Zahlungsunf\u00e4higkeit, drohende Zahlungsunf\u00e4higkeit, \u00dcberschuldung<\/li>\n<li>Insolvenzverschleppung \u2013 Strafbarkeit nach \u00a7 15a Abs. 4 und 5<\/li>\n<li>InsO<\/li>\n<li>Ablauf des Insolvenzverfahrens<\/li>\n<li>Er\u00f6ffnungsverfahren, Gl\u00e4ubigerversammlung, Verwaltung und Verwertung der Insolvenzmasse, Verteilungs- und Schlussverfahren<\/li>\n<li>Arbeitsrecht im Insolvenzverfahren<\/li>\n<li>Eigenverwaltung und Sanierung (\u201eInsolvenz light\u201c)<\/li>\n<li>zB. Insolvenzplan (\u00a7\u00a7 217 ff. InsO), Schutzschirmverfahren (ESUG, \u00a7\u00a7 270 ff. InsO)<\/li>\n<li>Internationale Zust\u00e4ndigkeit des Insolvenzgerichts<\/li>\n<li>Art. 3 EuInsVO: vom satzungsm\u00e4\u00dfigen Sitz des Unternehmens abweichender Mittelpunkt der haupts\u00e4chlichen Interessen (Center of Main Interest\/COMI) in einem anderen EU-Mitgliedsstaat (ca. 3 \u00bd Stunden)<\/li>\n<\/ul>\n<h4>England und Wales<\/h4>\n<ul>\n<li>Rechtsgrundlagen<\/li>\n<li>Aufgaben von receiver und administrator<\/li>\n<li>Arten und Ablauf des Verfahrens anhand von Beispielf\u00e4llen<\/li>\n<li>Freiwilliger au\u00dfergerichtlicher Vergleich: Company Voluntary Arrangement (Insolvency Act Ss. 1-7)<\/li>\n<li>Administration (Insolvency Act Schedule B1)<\/li>\n<\/ul>\n<h4>USA<\/h4>\n<p>Sanierung nach Chapter 11<br>Title 11 Chapter 11 United States Code, auch als Bankruptcy Code bezeichnet: Restrukturierung, Schutz vor den Forderungen der Gl\u00e4ubiger<br>(Angloamerikanischer Rechtskreis &#8211; zusammen ca. 1 \u00be Stunden) &#8211; BD\u00dc, 2014<\/p>\n<p>Deutsches Immobilienrecht DE &gt; EN\/US, Vom-Blatt-\u00dcbersetzen in Notariaten: der beurkundete Grundst\u00fcckskaufvertrag &amp; Bestellung einer Grundschuld, Weiterbildung bei einer sehr erfahrenen \u00dcbersetzerin und Dolmetscherin aus den USA mit langj\u00e4hrigem Wohnsitz Deutschland &#8211; BD\u00dc, 2014<\/p>\n<p>Datenschutz-Update 2017 einschlie\u00dflich EU-Datenschutz-Grundverordnung (DS-GVO) mit Schwerpunkt \u00abAnforderungen f\u00fcr freiberufliche \u00dcbersetzer\u00bb &#8211;&nbsp; BD\u00dc<\/p>\n<h3>Juristische \u00dcbersetzung Spanisch<\/h3>\n<p>\u00dcbersetzen spanischer Rechtstexte (BD\u00dc) \u2013 2008<\/p>\n<p>\u00dcbersetzung DE &lt;&gt; ES von Gerichtsdokumenten, notariellen Urkunden, gesellschaftsrechtlichen Vertr\u00e4gen und arbeitsrechtlichen Unterlagen bei einer zweisprachigen spanischen Rechtsanw\u00e4ltin, Instituto Cervantes &#8211; 2009\/2010 &#8211; Gesamtumfang 25 Stunden<br>Spanisches Ehe- und Scheidungsrecht (BD\u00dc) \u2013 2012<\/p>\n<h3>Juristische \u00dcbersetzung Portugiesisch<\/h3>\n<p>\u00dcbersetzen brasilianischer und portugiesischer Rechtstexte\/Urkunden (ATICOM Berufsverband) \u2013 2009<\/p>\n<h3>\u00dcbersetzen im Bereich Rechnungslegung\/Finanzberichterstattung &amp; Steuerrecht<\/h3>\n<p>Rechnungslegung nach IFRS\/HGB, zweit\u00e4giges Seminar f\u00fcr DE &lt;&gt; EN-\u00dcbersetzer, Dt. Terminologie-Tag \u2013 2009<\/p>\n<p>Gasth\u00f6rer Uni Bielefeld: Vorlesungen Rechnungslegung &#8211; 2010-2011<\/p>\n<p>Rechnungslegung nach IFRS\/US-GAAP\/HGB, EN &lt;&gt; DE &#8211; 2t\u00e4giges Weiterbildungsmodul an der<br>City University, London &#8211; 2011<\/p>\n<p>Terminologie EN &gt; DE von Jahres- und Konzernabschl\u00fcssen sowie Hintergrundinformationen und \u00dcbersetzungs\u00fcbungen; Vergleich IFRS- mit HGB-Rechnungslegung (BD\u00dc) \u2013 2012<\/p>\n<p>Stil- und Registerregeln f\u00fcr die \u00dcbersetzung von Gesch\u00e4ftsberichten DE &gt; EN \u2013 BD\u00dc-Konferenz 2012<\/p>\n<p>Terminologie EN &lt;&gt; DE von Jahres- und Konzernabschl\u00fcssen nach IFRS sowie Hintergrundinformationen und \u00dcbersetzungs\u00fcbungen &#8211; Vertiefung (BD\u00dc) &#8211; 2013<\/p>\n<p>Meisterkurs Gesch\u00e4ftsberichte nach IFRS &amp; DRS: stilistische Aspekte und Terminologie DE &gt; EN, Hintergrundinformationen in Englisch, insbesondere zu den Themen Konsolidierung bzw. Corporate Governance, postenweise Durchsicht der zugeh\u00f6rigen prim\u00e4ren Abschlussbestandteile ausgew\u00e4hlter deutscher Konzerne DE &gt; EN, 2 Tage (BD\u00dc) \u2013 2013<\/p>\n<p>Optimale Datenerfassung mit dem WISO Steuer-Sparbuch, als erstes von 5 Webinaren im 1. Quartal 2014 zu verschiedenen Themen mit dem Ziel, den teilnehmenden WISO-Abonnenten n\u00e4herzubringen, wie sie ihre Steuererkl\u00e4rung mit WISO-Software im Hinblick auf eine steueroptimale Gestaltung kompetent selbst machen k\u00f6nnen. Ziel dieser Weiterbildungsreihe ist es, auf Sebastians bereits guten Kenntnissen im Steuerrecht aufbauend, ihn fachlich mit der WISO-Expertin Astrid auf Augenh\u00f6he zu bringen.<\/p>\n<p>Umwandlungssteuergesetz: Umwandlung von Kapitalgesellschaften: z.B. Arten von Transaktionen &#8211; bisher 85 Min., Kurs wird fortgesetzt (Lecturio) &#8211; 2014<\/p>\n<h3>\u00dcbersetzungen f\u00fcr den Finanzsektor, Volkswirtschaft\/Geld- und W\u00e4hrungspolitik<\/h3>\n<p>Terminologie DE &lt;&gt; EN und Hintergrundinformationen zu den Finanzm\u00e4rkten (BD\u00dc) \u2013 2010<\/p>\n<p>Finanzm\u00e4rkte, Aufsichtsbeh\u00f6rden und Marktteilnehmer EN &lt;&gt; DE &#8211; 2t\u00e4giges Weiterbildungsmodul an der<br>City University, London &#8211; 2011<\/p>\n<p>Fremdw\u00e4hrungsmanagement &amp; Devisenhandel (DE &lt;&gt; EN) (BD\u00dc) &#8211; 2012<\/p>\n<p>Notenbankwesen: DE &gt; EN-Praxisseminar eines angestellten \u00dcbersetzers der Bundesbank aus den USA &#8211; BD\u00dc-Konferenz 2012<\/p>\n<p>\u00dcberblick \u00fcber den deutschen Finanzmarkt (Deutsche B\u00f6rse Group, 65760 Eschborn) &#8211; 2013:<\/p>\n<p>Zum \u00abAufw\u00e4rmen\u00bb: Besuch des Geldmuseums der Bundesbank in Frankfurt\/Main<\/p>\n<p>Inhalts\u00fcberblick Seminar<\/p>\n<ul>\n<li>Definition und Abgrenzung des Begriffs Finanzmarkt<\/li>\n<li>Die verschiedenen M\u00e4rkte im \u00dcberblick<\/li>\n<li>Geldmarkt, Kapitalmarkt, Devisenmarkt<\/li>\n<\/ul>\n<p>Marktteilnehmer:<\/p>\n<ul>\n<li>Unterscheidung nach dem Kreditwesengesetz<\/li>\n<li>Banken<\/li>\n<li>Fondsgesellschaften<\/li>\n<li>Private und institutionelle Anleger<\/li>\n<li>Aufgaben und Organisation der Deutschen Bundesbank und der Europ\u00e4ischen Zentralbank<\/li>\n<\/ul>\n<p>Die B\u00f6rse:<\/p>\n<ul>\n<li>Definition<\/li>\n<li>B\u00f6rsenstruktur in Deutschland<\/li>\n<li>Kassamarkt<\/li>\n<li>Terminmarkt<\/li>\n<\/ul>\n<ul>\n<li>Aufsicht und Anlegerschutz in Deutschland<\/li>\n<li>Rechtliche Grundlagen f\u00fcr den B\u00f6rsenhandel<\/li>\n<\/ul>\n<p>4 Webinare im Umfang von zusammen 4,5 Stunden mit Dr. Gregor Bauer, Dozent f\u00fcr Technische Analyse und Portfolio Management an der Frankfurt School of Finance &amp; Management &#8211; Cortal Consors, 2014:<br>Besser anlegen: Strategien und Praxistipps<\/p>\n<ul>\n<li>Anleihen<\/li>\n<li>Exchange Traded Products\/ETPs: Exchange Traded Funds\/ETFs, Exchange Traded Commodities\/ETCs und Exchange Traded Notes\/ETNs (b\u00f6rsengehandelte, in vielen F\u00e4llen nicht aktiv gemanagte Instrumente)<\/li>\n<li>Klassische Investmentfonds (aktiv gemanagt)<\/li>\n<li>Optionsscheine<\/li>\n<\/ul>\n<p>Derivatives &#8211; Webinar zum Investieren in verschiedene Finanzinstrumente (Basiswerte) mittels Derivaten, in Englisch:<\/p>\n<p>Im Webinar vorgestellte Arten der Konstruktion: 1. Terminkontrakte: Forwards &amp; Futures, 2. Optionen 3. Swaps (Zinsswaps\/W\u00e4hrungsswaps)<\/p>\n<p>Im Webinar vorgestellte Basiswerte: Aktien, Indizes, Rohstoffe, W\u00e4hrungen<\/p>\n<p>Wie funktioniert eine Option? Wie funktionieren Forwards bzw. Futures? &#8211; Lebenspraktische Beispiele, z.B. zur Veranschaulichung eines Terminkontraktes: Kauf bzw. Verkauf von Pferden zu einem jetzt festgemachten Preis mit Erf\u00fcllung (settlement) an einem festgelegten Termin in der Zukunft, an dem die vierbeinigen \u00abBasiswerte\u00bb an den K\u00e4ufer des Papiers, also des Terminkontraktes, geliefert (bei Kauf) bzw. von ihm geliefert werden (bei Verkauf) m\u00fcssen, um sich gegen Preisschwankungen auf dem Pferdemarkt abzusichern, denn die Tiere k\u00f6nnten ja bald mehr kosten am Markt (dagegen will sich der Termink\u00e4ufer sch\u00fctzen) bzw. die k\u00f6nnten ja im Rahmen einer Tier-Epidemie stark an Wert verlieren (dagegen will sich der Terminverk\u00e4ufer sch\u00fctzen).<\/p>\n<p>Wichtige Begriffe im Optionshandel: z.B. Verfallsdatum, amerikanische Option, europ\u00e4ische Option (eine amerikanische Option kann bis zum Verfallsdatum jederzeit ausge\u00fcbt werden, eine europ\u00e4ische Option nur am Verfalltag selbst), Aus\u00fcbungspreis\/Basispreis (strike price), Stillhalter (option seller\/writer), der die Option verkauft als Gegenpartei zum K\u00e4ufer der Option. Der Verk\u00e4ufer muss bis zur eventuellen Aus\u00fcbung der Option durch den K\u00e4ufer \u201estillhalten\u201c. W\u00e4hrend er bei einer Kaufoption den Basiswert bereit halten muss, falls dieser abgerufen wird, muss der Verk\u00e4ufer einer Option Geld bereit halten, um den Basiswert kaufen zu k\u00f6nnen.<\/p>\n<p>Unterschied zwischen Optionen und Terminkontrakten: der Kauf einer Option verleiht das Recht, den Basiswert zu kaufen oder zu verkaufen, mit dem Kauf eines Terminkontraktes verpflichtet sich der K\u00e4ufer, den Basiswert zu kaufen oder zu verkaufen.<\/p>\n<p>Call Option (Kaufoption)\/Put Option (Verkaufsoption)<\/p>\n<p>Long Call\/Short Call\/Long Put\/Short Put: Funktionsweise<br>Konkrete Rechenbeispiele Long Call\/Short Call\/Long Put\/Short Put in Excel, jeweils auf Basis des Schlusskurses des von India Index Services and Products (ISL) ver\u00f6ffentlichten, wichtigsten indischen Aktienindex Nifty, der 50 Werte sehr gro\u00dfer indischer Unternehmen aus 24 Wirtschaftssektoren umfasst, mit graphischer Darstellung als Chart (bis dato 55 Minuten, wird fortgesetzt) &#8211; Lecturio, 2014<\/p>\n<p>Aktuelle Entwicklungen in der EU-Finanzmarkt- und Bankenregulierung: European Market<\/p>\n<p>Infrastructure Regulation (EU-Verordnung zur Eind\u00e4mmung systemischer Risiken im europ\u00e4ischen Derivatemarkt, umfasst u. a. die Clearingpflicht f\u00fcr OTC-Derivate), zweigliedrige Comprehensive Assessment-Bankenpr\u00fcfung der EZB: Asset Quality Review-Verfahren (Werthaltigkeitspr\u00fcfung der Bankbilanzen) und Banken-Stresstest, einheitlicher Bankenaufsichtsmechanismus SSM, Finanzmarktrichtlinie MiFID II, wichtige Derivatehandels-Konzepte Kontrahentenrisiko (counterparty credit risk) und Transaktionsregister (Trade Repository), Margin vs. Collateral, Berechnung der Sicherheitsleistungen (Margining-Prozess), Kreditrisikovorsorge (credit risk provisioning), hartes Kernkapital (Common Equity Tier 1 capital) &#8211; Webinar \u00fcber \u00dcbersetzer-Fortbildungsplattform, 2015<\/p>\n<p>\u00dcbersetzung in Zusammenhang mit M&amp;A, Mergers and Acquisitions (Fusionen &amp; \u00dcbernahmen), Webinar bei einem Finanz\u00fcbersetzer f\u00fcr Englisch und Trainer, 2015<\/p>\n<p>Alternative Investments &#8211; Commerzbank-Webinar, 2017<\/p>\n<p>Finanzm\u00e4rkte aktuell: Theorie und Praxis, Consorsbank-Webinar, 2017&nbsp;<\/p>\n<h3>Diverse andere Wirtschaftsgebiete\/Technik\/sonstige Fachgebiete oder Themen\/Portugiesisch-Unterricht<\/h3>\n<p>\u00dcbersetzen im Bereich Erneuerbare Energien DE &gt; EN (Vortrag) &#8211; BD\u00dc-Konferenz 2012<\/p>\n<p>Gasth\u00f6rer Uni Bielefeld: div. Seminare Brasilianisches Portugiesisch &#8211; 2010-2012<\/p>\n<p>Webinar: Grundlagen der Personalwirtschaft: Personalbeschaffung, Personalentwicklung und -f\u00f6rderung (150 Minuten) &#8211; Lecturio, 2014<\/p>\n<p>Umwandlungssteuergesetz: Umwandlung von Kapitalgesellschaften: z.B. Arten von Transaktionen &#8211; bisher 85 Min., Kurs wird fortgesetzt (Lecturio) &#8211; 2014<\/p>\n<p>Technische \u00dcbersetzungen: der terminologische Ansatz (Webinar f\u00fcr ins Englische \u00dcbersetzende am Beispiel FR &gt; EN bei einem Professor der Physik aus Gro\u00dfbritannien, auf langj\u00e4hrige Nordamerika-Aufenthalte zur\u00fcckblickend) &#8211; 2014<\/p>\n<p>The Manufacturing Industry in the 21st Century &#8211; from boardroom to shop floor (75 min\u00fctige fundierte technische Einf\u00fchrung in die Welt der verarbeitenden Industrie), eCPD Webinars, 2014<\/p>\n<p>Versicherungsterminologie lernen und verstehen &#8211; Franz\u00f6sisch &gt; Britisches Englisch, 75min\u00fctiges Webinar mit einer britischen Franz\u00f6sisch &gt; Englisch-Dolmetscherin und \u00dcbersetzerin sowie Anw\u00e4ltin, Themen: Krankenversicherung, diverse KFZ-Versicherungen, Hausrat- und Hausversicherungen, 2016<\/p>\n<p>Gesch\u00e4ftschancen in Brasilien f\u00fcr deutsche Unternehmen aus der Abwasserwirtschaft, zweist\u00fcndiges Webinar f\u00fcr Firmen aus der GreenTech-Branche in englischer und deutscher Sprache bzw. zum Teil auch in portugiesischer Sprache, Auslandshandelskammer Rio de Janeiro, Brasilien, 2020<\/p>\n<p>Zielmarkt Brasilien f\u00fcr deutsche Unternehmen aus der Abwasserwirtschaft, zweist\u00fcndiges Webinar f\u00fcr Firmen aus der GreenTech-Branche in englischer Sprache, Auslandshandelskammer Rio de Janeiro, Brasilien, 2023<\/p>\n<p>Kooperationsformen f\u00fcr Dolmetscher und \u00dcbersetzer, Informationen \u00fcber haftungsrechtliche wie auch steuerliche Vor- und Nachteile sowie Zugangsvoraussetzungen der g\u00e4ngigsten bzw. von einigen der momentan noch weniger stark nachgefragten Rechtsformen f\u00fcr diesen Zweck, zwei mehrst\u00fcndige Webinaraufzeichnungen in dt. Sprache, BD\u00dc, 2021<\/p>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\">Dealing with Clients as a translator or interpreter, Webinar \u00fcber bew\u00e4hrte Verfahren im Kundenkontakt, Chartered Institute of Linguists, 2023<\/span><br><\/p>\n<p><\/p>\n<h3>Dolmetschen<\/h3>\n<p>Einw\u00f6chiges Seminar &#8216;Dolmetschen f\u00fcr Englisch\u00fcbersetzer&#8217; (FASK Germersheim der Uni Mainz) \u2013 2009<\/p>\n<p>Professionelles Verhalten vor Gericht f\u00fcr Dolmetscher (ATICOM) \u2013 2011<\/p>\n<h3>Arbeit mit \u00dcbersetzungsumgebungen (vom \u00dcbersetzer zu f\u00fcllende Satzdatenbanken) und darin integrierbaren Terminologieverwaltungen<\/h3>\n<p>\u00abWas sagen mir die Tags?\u00bb, Vortrag eines autorisierten SDL Trados-<br>Trainers zu Formatierungsanweisungen in SDL Trados Studio, Tagung der Sprachmittlerbranche in privater Tr\u00e4gerschaft f\u00fcr das Ruhrgebiet und die DACH-L\u00e4nder &#8211; 2010<\/p>\n<p>SDL Trados Studio 2009 Aufbaustufe (SDL-Webinar) \u2013 2010<\/p>\n<p>SDL Trados MultiTerm 2009 (SDL-Webinar) \u2013 2011<\/p>\n<p>SDL Trados Studio 2009 f\u00fcr Fortgeschrittene (BD\u00dc) \u2013 2011<\/p>\n<p>\u00abTell me all the ways freelance translators can get help and support from SDL\u00bb (Zeige mir, wie freiberufliche \u00dcbersetzer Hilfe und Unterst\u00fctzung von SDL erhalten k\u00f6nnen), SDL Webinar &#8211; 2019<\/p>\n<p>SDL Trados Studio Q&amp;A\/Frage&amp;Antwort-Webinar mit Paul Filkin, Client Services Director SDL &#8211; 2019<\/p>\n<p>SDL Trados Studio 2019 &#8211; Segmente zusammenf\u00fchren: wann ist es sinnvoll, wann nicht, und was ist beim Zusammenf\u00fchren sonst noch zu beachten. Webinar eines autorisierten SDL Trados-<br>Trainers &#8211; 2020<\/p>\n<p>Virtuelle SDL Trados Konferenz, 3 Tage Schulungen (auch zu&nbsp; MultiTerm) und Pr\u00e4sentationen zur Vertiefung des Hintergrundwissens bzw. zum Ausblick auf die zum Teil bereits heute verf\u00fcgbare CAT-Technologie der Zukunft, 2020<\/p>\n<div>\u00abDesktop-Fokus: Welchen Nutzen haben Dienstleister an den neuen Funktionen in SDL Trados Studio 2021?\u00bb, SDL Webinar &#8211; 2020<\/div>\n<div>&#8211; Mit Alt+Umschalt+A rasch alle Segmentstatus \u00e4ndern<\/div>\n<div>&#8211; Erweiterter Anzeigefilter 2.0<\/div>\n<div>&#8211; Neue leistungsf\u00e4hige, sprachvariet\u00e4tenabh\u00e4ngige und dennoch anpassbare Funktion zur Verwaltung von Datumsformaten<\/div>\n<div>&#8211; Erinnerung an die Verwendung regul\u00e4rer Ausdr\u00fccke (RegEx), um das Beste aus Studio herauszuholen<\/div>\n<div>&#8211; Erinnerung an die M\u00f6glichkeit, sich einen eigenen privaten AppStore einzurichten<\/div>\n<div>&#8211; Integration der SDL Community, der SDL Knowledge Base, des SDL AppStore und des SDL Support-Portals in Studio 2021<\/div>\n<div>&nbsp;<\/div>\n<p>Technical Live Q&amp;A zu SDL Trados Studio 2021, Fleur Schut, Business Consultant &amp; Paul Filkin, Client Services Director, RWS, Trados Virtual Conference, Mai 2021<br>Arbeit mit Trados-Paketen: Repetitorium und Tipps f\u00fcr Fortgeschrittene, Ziad Chama,&nbsp;RWS, Trados Virtual Conference, Mai 2021<br>Trados Sprachressourcen, Paul Filkin,&nbsp;Trados Virtual Conference, Mai 2021 &nbsp;<br>Studio 2021 Pfadmanagement (bez\u00fcglich Projektvorlagen etc.), zertifizierter Softwaretrainer, Loctimize GmbH<br>Projektmanagement mit RWS-Software as a Service wie z.B. \u00abTrados Live Team\u00bb, Lydia Simplicio, RWS<\/p>\n<p>MS Office-Anwendungen f\u00fcr Fortgeschrittene und Verwendung weiterer Programme (ausgenommen \u00dcbersetzungsumgebungen\/Terminologieverwaltungen)<\/p>\n<p>Abbyy FineReader und Formatvorlagen in Word 2007 effizient anwenden (AD\u00dc Nord-Praxisseminar) \u2013 2010<\/p>\n<p>Word 2007 Aufbaustufe: fortgeschrittene Bearbeitungs- und Formatierungsfunktionen, Arbeit mit Verzeichnissen, Fu\u00dfnoten und Kopfzeilen &#8211; New Horizons Computer Learning Centers \u2013 2010<\/p>\n<p>Word f\u00fcr \u00dcbersetzer: Formatierungen suchen und ersetzen und andere Tipps &amp; Tricks (Attila Pir\u00f3th PhD MSc) &#8211; 2010<\/p>\n<p>Word 2013, Webinar eines autorisierten SDL Trados-Trainers \u00fcber ein Freiburger Fortbildungsportal f\u00fcr \u00dcbersetzer &#8211; 2014<\/p>\n<p>MS Access Grundlagen f\u00fcr Anwender, Malte Koch Computerschulung D\u00fcsseldorf &#8211; 2015<\/p>\n<p><span style=\"font-style: inherit; font-weight: inherit;\"><br><\/span><\/p><p><span style=\"font-style: inherit; font-weight: inherit;\">Teilnahmebescheinigungen auf Anfrage einsehbar<\/span><br><\/p>\n<p><br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fortbildung &amp; Aktuelles Aktuelles \u00c4nderungen unserer AGB in \u00a7 3c zu Mindestauftragswerten &#8211; 2013 \u00c4nderungen unserer AGB in \u00a7 3a zu den Berechnungsgrundlagen unserer Leistungen und \u00a7 4a und 4d zu den Zahlungskonditionen &#8211; 2014 \u00c4nderungen unserer AGB in \u00a7 5 zu den R\u00fccktrittsregelungen und \u00a7 7 zu Stornierungsgeb\u00fchren &#8211; 2014 \u00c4nderung unserer AGB in [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":723,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-826","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fortbildung &amp; Aktuelles - A. &amp; S. Witte Partnerschaft<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fortbildung &amp; Aktuelles - A. &amp; S. Witte Partnerschaft\" \/>\n<meta property=\"og:description\" content=\"Fortbildung &amp; Aktuelles Aktuelles \u00c4nderungen unserer AGB in \u00a7 3c zu Mindestauftragswerten &#8211; 2013 \u00c4nderungen unserer AGB in \u00a7 3a zu den Berechnungsgrundlagen unserer Leistungen und \u00a7 4a und 4d zu den Zahlungskonditionen &#8211; 2014 \u00c4nderungen unserer AGB in \u00a7 5 zu den R\u00fccktrittsregelungen und \u00a7 7 zu Stornierungsgeb\u00fchren &#8211; 2014 \u00c4nderung unserer AGB in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/\" \/>\n<meta property=\"og:site_name\" content=\"A. &amp; S. Witte Partnerschaft\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ASWITTE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-18T14:05:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/hoersaal-tmp.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/es\\\/servicios\\\/weiterbildung-aktuelles\\\/\",\"url\":\"https:\\\/\\\/aswittepartg.de\\\/es\\\/servicios\\\/weiterbildung-aktuelles\\\/\",\"name\":\"Fortbildung &amp; Aktuelles - A. &amp; S. Witte Partnerschaft\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/es\\\/servicios\\\/weiterbildung-aktuelles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/es\\\/servicios\\\/weiterbildung-aktuelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aswittepartg.de\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/hoersaal-tmp.jpg\",\"datePublished\":\"2023-06-25T20:16:44+00:00\",\"dateModified\":\"2024-08-18T14:05:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/es\\\/servicios\\\/weiterbildung-aktuelles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aswittepartg.de\\\/es\\\/servicios\\\/weiterbildung-aktuelles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/es\\\/servicios\\\/weiterbildung-aktuelles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aswittepartg.de\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/hoersaal-tmp.jpg\",\"contentUrl\":\"https:\\\/\\\/aswittepartg.de\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/hoersaal-tmp.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/es\\\/servicios\\\/weiterbildung-aktuelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aswittepartg.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios\",\"item\":\"https:\\\/\\\/aswittepartg.de\\\/servicios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fortbildung &amp; Aktuelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/#website\",\"url\":\"https:\\\/\\\/aswittepartg.de\\\/\",\"name\":\"A. & S. Witte Partnerschaft\",\"description\":\"Fach&uuml;bersetzungen\\\/Specialist translations\",\"publisher\":{\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/#organization\"},\"alternateName\":\"ASWITTE PartG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aswittepartg.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/#organization\",\"name\":\"A. & S. Witte Partnerschaft\",\"alternateName\":\"ASWITTE PartG\",\"url\":\"https:\\\/\\\/aswittepartg.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aswittepartg.de\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/aswittepartg.de\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"width\":457,\"height\":475,\"caption\":\"A. & S. Witte Partnerschaft\"},\"image\":{\"@id\":\"https:\\\/\\\/aswittepartg.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ASWITTE\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fortbildung &amp; Aktuelles - A. &amp; S. Witte Partnerschaft","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/","og_locale":"es_ES","og_type":"article","og_title":"Fortbildung &amp; Aktuelles - A. &amp; S. Witte Partnerschaft","og_description":"Fortbildung &amp; Aktuelles Aktuelles \u00c4nderungen unserer AGB in \u00a7 3c zu Mindestauftragswerten &#8211; 2013 \u00c4nderungen unserer AGB in \u00a7 3a zu den Berechnungsgrundlagen unserer Leistungen und \u00a7 4a und 4d zu den Zahlungskonditionen &#8211; 2014 \u00c4nderungen unserer AGB in \u00a7 5 zu den R\u00fccktrittsregelungen und \u00a7 7 zu Stornierungsgeb\u00fchren &#8211; 2014 \u00c4nderung unserer AGB in [&hellip;]","og_url":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/","og_site_name":"A. &amp; S. Witte Partnerschaft","article_publisher":"https:\/\/www.facebook.com\/ASWITTE","article_modified_time":"2024-08-18T14:05:39+00:00","og_image":[{"url":"https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/hoersaal-tmp.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/","url":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/","name":"Fortbildung &amp; Aktuelles - A. &amp; S. Witte Partnerschaft","isPartOf":{"@id":"https:\/\/aswittepartg.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/#primaryimage"},"image":{"@id":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/#primaryimage"},"thumbnailUrl":"https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/hoersaal-tmp.jpg","datePublished":"2023-06-25T20:16:44+00:00","dateModified":"2024-08-18T14:05:39+00:00","breadcrumb":{"@id":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/#primaryimage","url":"https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/hoersaal-tmp.jpg","contentUrl":"https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/hoersaal-tmp.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/aswittepartg.de\/es\/servicios\/weiterbildung-aktuelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aswittepartg.de\/es\/"},{"@type":"ListItem","position":2,"name":"Servicios","item":"https:\/\/aswittepartg.de\/servicios\/"},{"@type":"ListItem","position":3,"name":"Fortbildung &amp; Aktuelles"}]},{"@type":"WebSite","@id":"https:\/\/aswittepartg.de\/#website","url":"https:\/\/aswittepartg.de\/","name":"A. & S. Witte Partnerschaft","description":"Fach&uuml;bersetzungen\/Specialist translations","publisher":{"@id":"https:\/\/aswittepartg.de\/#organization"},"alternateName":"ASWITTE PartG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aswittepartg.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aswittepartg.de\/#organization","name":"A. & S. Witte Partnerschaft","alternateName":"ASWITTE PartG","url":"https:\/\/aswittepartg.de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aswittepartg.de\/#\/schema\/logo\/image\/","url":"https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/logo.png","contentUrl":"https:\/\/aswittepartg.de\/wp-content\/uploads\/2023\/06\/logo.png","width":457,"height":475,"caption":"A. & S. Witte Partnerschaft"},"image":{"@id":"https:\/\/aswittepartg.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ASWITTE"]}]}},"_links":{"self":[{"href":"https:\/\/aswittepartg.de\/es\/wp-json\/wp\/v2\/pages\/826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aswittepartg.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aswittepartg.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aswittepartg.de\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aswittepartg.de\/es\/wp-json\/wp\/v2\/comments?post=826"}],"version-history":[{"count":28,"href":"https:\/\/aswittepartg.de\/es\/wp-json\/wp\/v2\/pages\/826\/revisions"}],"predecessor-version":[{"id":1685,"href":"https:\/\/aswittepartg.de\/es\/wp-json\/wp\/v2\/pages\/826\/revisions\/1685"}],"up":[{"embeddable":true,"href":"https:\/\/aswittepartg.de\/es\/wp-json\/wp\/v2\/pages\/723"}],"wp:attachment":[{"href":"https:\/\/aswittepartg.de\/es\/wp-json\/wp\/v2\/media?parent=826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}